{"id":1135,"date":"2021-07-13T09:36:36","date_gmt":"2021-07-13T09:36:36","guid":{"rendered":"https:\/\/hnwoodmachine.com\/?p=1135"},"modified":"2021-07-17T01:29:38","modified_gmt":"2021-07-17T01:29:38","slug":"what-problems-should-be-paid-attention-to-in-the-installation-of-the-wood-crusher","status":"publish","type":"post","link":"https:\/\/hnwoodmachine.com\/pt\/what-problems-should-be-paid-attention-to-in-the-installation-of-the-wood-crusher\/","title":{"rendered":"A quais problemas devemos prestar aten\u00e7\u00e3o na instala\u00e7\u00e3o do triturador de madeira?"},"content":{"rendered":"<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-top\"     data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;1135&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;22&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.8&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.8\\\/5 - (22 votes)&quot;,&quot;size&quot;:&quot;25&quot;,&quot;title&quot;:&quot;What problems should be paid attention to in the installation of the wood crusher?&quot;,&quot;width&quot;:&quot;141.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 141.5px;\">             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 20px;\">             4.8\/5 - (22 votos)    <\/div>     <\/div>  <p class=\"translation-block\">Embora a estrutura do grande <strong><a href=\"https:\/\/hnwoodmachine.com\/pt\/wood-crusher-wood-shredder\/\">triturador de madeira<\/a><\/strong> seja muito simples, a instala\u00e7\u00e3o e a depura\u00e7\u00e3o n\u00e3o s\u00e3o uma quest\u00e3o simples. Se houver uma ligeira omiss\u00e3o, isso ir\u00e1 criar v\u00e1rios perigos de seguran\u00e7a no futuro.<\/p>    <ul class=\"wp-block-list\"><li>A largura de entrada do equipamento de alimenta\u00e7\u00e3o e do triturador deve ser a mesma para garantir que o material seja distribu\u00eddo uniformemente ao entrar no triturador de madeira; os dois devem ser conectados suavemente, o que favorece o funcionamento est\u00e1vel do alimentador e n\u00e3o \u00e9 afetado pela vibra\u00e7\u00e3o do triturador de madeira. Entra um bom fluxo de material.<\/li><li>N\u00e3o deixe cair as pe\u00e7as no ch\u00e3o \u00e0 vontade durante a instala\u00e7\u00e3o para evitar a deforma\u00e7\u00e3o das pe\u00e7as, principalmente a deforma\u00e7\u00e3o da tubula\u00e7\u00e3o. Depois que a tubula\u00e7\u00e3o for deformada, isso causar\u00e1 problemas na conex\u00e3o com outras pe\u00e7as. Os parafusos de conex\u00e3o devem ser apertados, especialmente se for um elo de parafuso em um local alto. Deve atender aos requisitos de uso. Se houver um problema, ser\u00e1 muito dif\u00edcil mant\u00ea-lo. A veda\u00e7\u00e3o de cada conex\u00e3o deve ser bem feita para evitar a entrada de poeira;<\/li><li>O layout da linha deve ser bem feito, a extremidade da linha n\u00e3o deve ficar exposta do lado de fora e a linha deve ser organizada razoavelmente de acordo com o ambiente do local. A tens\u00e3o utilizada pelo motor do equipamento \u00e9 de 380V, o que \u00e9 extremamente prejudicial ao corpo humano. A seguran\u00e7a deve ser considerada durante o layout e deve ser conveniente para uso pelos operadores;<\/li><li>Ao testar a m\u00e1quina, observe e ou\u00e7a atentamente, observe se o equipamento balan\u00e7a e ou\u00e7a se h\u00e1 algum ru\u00eddo no equipamento. Caso haja alguma anormalidade, deve-se deslig\u00e1-lo e verific\u00e1-lo imediatamente para remover os obst\u00e1culos, para que o equipamento possa obter resultados satisfat\u00f3rios quando for oficialmente utilizado.<\/li><li>Ao instalar o processo de descarga mec\u00e2nica, deve haver espa\u00e7o suficiente na c\u00e2mara de decanta\u00e7\u00e3o do p\u00f3 para atender ao afundamento suficiente do p\u00f3 durante a remo\u00e7\u00e3o do p\u00f3. \u00c9 melhor instalar uma divis\u00f3ria na c\u00e2mara de decanta\u00e7\u00e3o (entre o moedor e o coletor de p\u00f3). ), o tamanho da divis\u00f3ria \u00e9 geralmente 1\/3 da altura da c\u00e2mara de sedimenta\u00e7\u00e3o, que \u00e9 usada para evitar que mais p\u00f3 entre no coletor de p\u00f3, deixando mais tempo para o p\u00f3 afundar.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Embora a estrutura do grande triturador de madeira seja muito simples, a instala\u00e7\u00e3o e depura\u00e7\u00e3o n\u00e3o s\u00e3o uma quest\u00e3o simples. Se houver uma ligeira omiss\u00e3o, v\u00e1rios riscos de seguran\u00e7a ser\u00e3o ocultados no uso futuro.<\/p>","protected":false},"author":1,"featured_media":1145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"taxonomy_info":{"category":[{"value":1,"label":"News"}]},"featured_image_src_large":["https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/07\/working-scene1-1.jpg.jpg",720,405,false],"author_info":{"display_name":"HN-WOOD","author_link":"https:\/\/hnwoodmachine.com\/pt\/author\/woodmachine\/"},"comment_info":0,"category_info":[{"term_id":1,"name":"News","slug":"news","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":45,"filter":"raw","cat_ID":1,"category_count":45,"category_description":"","cat_name":"News","category_nicename":"news","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/posts\/1135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":0,"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/posts\/1135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/media\/1145"}],"wp:attachment":[{"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/media?parent=1135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/categories?post=1135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hnwoodmachine.com\/pt\/wp-json\/wp\/v2\/tags?post=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}