{"id":902,"date":"2021-05-17T10:25:31","date_gmt":"2021-05-17T10:25:31","guid":{"rendered":"https:\/\/hnwoodmachine.com\/?p=902"},"modified":"2023-12-08T13:56:39","modified_gmt":"2023-12-08T05:56:39","slug":"compressed-wood-block-making-machine","status":"publish","type":"post","link":"https:\/\/hnwoodmachine.com\/fr\/compressed-wood-block-making-machine\/","title":{"rendered":"Machine de fabrication de blocs de palettes en bois de sciure de bois | Machine \u00e0 blocs de bois compress\u00e9"},"content":{"rendered":"<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-top\"     data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;902&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;24&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.8&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.8\\\/5 - (24 votes)&quot;,&quot;size&quot;:&quot;25&quot;,&quot;title&quot;:&quot;Sawdust Wood Pallet Block Making Machine | Compressed Wood Block Machine&quot;,&quot;width&quot;:&quot;141.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 141.5px;\">             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 25px; height: 25px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 20px;\">             4,8\/5 - (24 votes)    <\/div>     <\/div>  <p class=\"wp-block-paragraph\">L'\u00e9quipement de fabrication de blocs de palettes en bois utilise des d\u00e9chets tels que des copeaux de bois, des copeaux et de la paille comme mati\u00e8res premi\u00e8res pour produire des cales de palettes par s\u00e9chage, m\u00e9lange de colle et presse \u00e0 chaud pour le chauffage et la pressurisation. La plupart des mati\u00e8res premi\u00e8res sont des d\u00e9chets g\u00e9n\u00e9r\u00e9s lors de la transformation du bois, de sorte que les cales de pied de palette finales sont \u00e9galement un produit respectueux de l'environnement. De plus, le bloc de palette en bois form\u00e9 apr\u00e8s une temp\u00e9rature et une pression \u00e9lev\u00e9es a une duret\u00e9 comparable \u00e0 celle des mat\u00e9riaux en bois massif ordinaires. L'aspect est lisse et plat, c'est un mat\u00e9riau id\u00e9al pour r\u00e9aliser des repose-pieds et des jambes sur palettes en bois. Notre machine de fabrication de blocs de bois comprim\u00e9 peut \u00eatre personnalis\u00e9e en taille en fonction des besoins du client, et la pression et la densit\u00e9 du bloc de bois peuvent \u00e9galement \u00eatre ajust\u00e9es. C\u2019est une machine de haute qualit\u00e9 qui r\u00e9pond r\u00e9ellement aux besoins du client.<\/p>    <h2 class=\"wp-block-heading\" id=\"h-the-structure-of-the-compressed-wood-block-making-machine\"><strong>La structure de la machine de fabrication de blocs de bois comprim\u00e9<\/strong><\/h2>    <p class=\"wp-block-paragraph\">Notre machine de fabrication de blocs de bois comprim\u00e9 est principalement compos\u00e9e d'un dispositif de m\u00e9lange de colle, d'un syst\u00e8me de contr\u00f4le, d'un syst\u00e8me hydraulique et d'un syst\u00e8me de chauffage. Mettez les copeaux ou copeaux de bois s\u00e9ch\u00e9s dans le m\u00e9langeur de colle, puis ajoutez la r\u00e9sine ur\u00e9e-formald\u00e9hyde pour le m\u00e9lange. Le mat\u00e9riau entre par l'orifice d'alimentation et p\u00e9n\u00e8tre dans le r\u00e9servoir hydraulique en dessous sous l'action de la vis. Le syst\u00e8me hydraulique presse les mat\u00e9riaux m\u00e9lang\u00e9s dans et hors du dispositif de d\u00e9chargement, et le dispositif de d\u00e9chargement contient un syst\u00e8me de chauffage. La lignine contenue dans les mat\u00e9riaux est dissoute dans des conditions de temp\u00e9rature et de pression \u00e9lev\u00e9es afin que les mat\u00e9riaux soient \u00e9troitement li\u00e9s les uns aux autres et soient finalement form\u00e9s \u00e0 la sortie des bandes de bois. <\/p>    <div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"884\" height=\"500\" src=\"https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/structure-chart.jpg\" alt=\"organigramme\" class=\"wp-image-937\" title=\"\" srcset=\"https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/structure-chart.jpg 884w, https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/structure-chart-300x170.jpg 300w, https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/structure-chart-768x434.jpg 768w\" sizes=\"(max-width: 884px) 100vw, 884px\" \/><figcaption>organigramme<\/figcaption><\/figure><\/div>    <ol class=\"wp-block-list\"><li>Le panneau de commande peut contr\u00f4ler l'entra\u00eenement hydraulique et la temp\u00e9rature de la machine<\/li><li>Cette pi\u00e8ce\u00a0est le\u00a0syst\u00e8me hydraulique, la petite pi\u00e8ce ronde est un manom\u00e8tre<\/li><li>Il s'agit du dispositif de d\u00e9chargement, qui comporte une agitation en spirale \u00e0 l'int\u00e9rieur pour faciliter le d\u00e9chargement.<\/li><li>La plaque chauffante est \u00e0 l'int\u00e9rieur de cette partie, la temp\u00e9rature est d'environ 200 degr\u00e9s<\/li><li>Le produit final se d\u00e9chargera ici et la pression peut \u00eatre ajust\u00e9e par les vis environnantes<\/li><li>Les bandes de bois peuvent \u00eatre \u00e9quip\u00e9es d'une machine de d\u00e9coupe de blocs sp\u00e9ciale selon les besoins du client<\/li><\/ol>    <h2 class=\"wp-block-heading\" id=\"h-the-advantages-of-the-wood-pallet-block-making-machine\"><strong>Les avantages de la machine de fabrication de blocs de palettes en bois<\/strong><\/h2>    <ul class=\"wp-block-list\"><li>Les mati\u00e8res premi\u00e8res sont des d\u00e9chets de copeaux de bois issus du processus de transformation du bois, et les produits fabriqu\u00e9s sont exempts d'inspection et de fumigation, ce qui est un produit respectueux de l'environnement.<\/li><li>La surface du bloc de bois produit est lisse et plate, imperm\u00e9able et difficile \u00e0 fissurer.<\/li><li>Le moule peut \u00eatre personnalis\u00e9 selon les exigences du client. La densit\u00e9 du bloc de bois peut \u00eatre ajust\u00e9e, jusqu'\u00e0 700kg\/m<sup>3<\/sup>, et il est solide et ne peut pas \u00eatre clou\u00e9.<\/li><li>La structure de l'\u00e9quipement est simple, facile \u00e0 utiliser, conforme au concept de d\u00e9veloppement durable et offre de larges perspectives de march\u00e9.<\/li><\/ul>    <div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1008\" height=\"633\" src=\"https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/Factory-display-2.jpg\" alt=\"Affichage d&#039;usine\" class=\"wp-image-936\" title=\"\" srcset=\"https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/Factory-display-2.jpg 1008w, https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/Factory-display-2-300x188.jpg 300w, https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/Factory-display-2-768x482.jpg 768w\" sizes=\"(max-width: 1008px) 100vw, 1008px\" \/><figcaption>Affichage d'usine<\/figcaption><\/figure><\/div>    <h2 class=\"wp-block-heading\" id=\"h-applications-of-the-wood-pallet-block\"><strong>Applications du bloc de palette en bois<\/strong><\/h2>    <p class=\"wp-block-paragraph\">Les blocs de palettes en bois\u00a0sont principalement utilis\u00e9s dans l'industrie du transport, ce qui peut jouer un bon r\u00f4le de protection. Il est largement utilis\u00e9 dans l'emballage ext\u00e9rieur et le traitement des palettes pour le transport de produits dans les domaines de la logistique, des machines et de l'\u00e9lectronique, des mat\u00e9riaux de construction en c\u00e9ramique, du mat\u00e9riel et des appareils \u00e9lectriques, des instruments de pr\u00e9cision, des mines, de l'acier, du transport maritime et d'autres industries.<\/p>    <div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"489\" src=\"https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/Applications-1024x489.jpg\" alt=\"Applications\" class=\"wp-image-942\" title=\"\" srcset=\"https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/Applications-1024x489.jpg 1024w, https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/Applications-300x143.jpg 300w, https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/Applications-768x367.jpg 768w, https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/Applications.jpg 1120w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Applications<\/figcaption><\/figure><\/div>    <h2 class=\"wp-block-heading\" id=\"h-parameter-of-the-woodblock-making-machine\"><strong>Param\u00e8tre de la machine de fabrication de blocs de bois<\/strong><\/h2>    <p class=\"wp-block-paragraph\">La machine sera \u00e9quip\u00e9e d'un syst\u00e8me hydraulique et de deux machines de d\u00e9coupe<\/p>    <figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><strong>Mod\u00e8le<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Taille (mm)<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Puissance (kw)<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Capacit\u00e9(m<sup>3<\/sup>\/24h)<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Densit\u00e9(kg\/m<sup>3<\/sup>)<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Dimension(mm)<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Poids (kg<\/strong>)<\/td><\/tr><tr><td>WD-75<\/td><td class=\"has-text-align-center\" data-align=\"center\">75*75<\/td><td class=\"has-text-align-center\" data-align=\"center\">15<\/td><td class=\"has-text-align-center\" data-align=\"center\">3.5<\/td><td class=\"has-text-align-center\" data-align=\"center\">550-600<\/td><td class=\"has-text-align-center\" data-align=\"center\">4500*750*1200<\/td><td class=\"has-text-align-center\" data-align=\"center\">1300<\/td><\/tr><tr><td>WD-90<\/td><td class=\"has-text-align-center\" data-align=\"center\">90*90<\/td><td class=\"has-text-align-center\" data-align=\"center\">15<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">550-600<\/td><td class=\"has-text-align-center\" data-align=\"center\">4800*900*1200<\/td><td class=\"has-text-align-center\" data-align=\"center\">1500<\/td><\/tr><tr><td>WD-100<\/td><td class=\"has-text-align-center\" data-align=\"center\">100*100<\/td><td class=\"has-text-align-center\" data-align=\"center\">16<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">550-600<\/td><td class=\"has-text-align-center\" data-align=\"center\">5000*1000*1200<\/td><td class=\"has-text-align-center\" data-align=\"center\">1800<\/td><\/tr><tr><td>WD-120<\/td><td class=\"has-text-align-center\" data-align=\"center\">120*120<\/td><td class=\"has-text-align-center\" data-align=\"center\">18<\/td><td class=\"has-text-align-center\" data-align=\"center\">9<\/td><td class=\"has-text-align-center\" data-align=\"center\">550-600<\/td><td class=\"has-text-align-center\" data-align=\"center\">5500*1200*1200<\/td><td class=\"has-text-align-center\" data-align=\"center\">2000<\/td><\/tr><\/tbody><\/table><figcaption>Liste des param\u00e8tres<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\" id=\"h-operating-video-of-the-sawdust-wood-pallet-block-making-machine\">Vid\u00e9o de fonctionnement de la machine de fabrication de blocs de palettes en bois de sciure de bois<\/h2>    <figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"> <iframe title=\"Ligne de fabrication de blocs de palettes en bois de sciure de bois | Machine de fabrication de blocs de bois comprim\u00e9\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/468tFj4KhZQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe> <\/div><figcaption>Machine de fabrication de blocs de bois<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>L'\u00e9quipement de fabrication de blocs de palettes en bois utilise des d\u00e9chets tels que des copeaux de bois, des copeaux et de la paille comme mati\u00e8res premi\u00e8res pour produire des cales de palettes par s\u00e9chage, m\u00e9lange de colle et presse \u00e0 chaud pour le chauffage et la pressurisation. <\/p>","protected":false},"author":1,"featured_media":940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"categories":[4],"tags":[75,31,30,74,41],"class_list":["post-902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product","tag-packaging-materials","tag-wood-block","tag-wood-dust","tag-wood-pallet-block","tag-wood-shaving"],"taxonomy_info":{"category":[{"value":4,"label":"Product"}],"post_tag":[{"value":75,"label":"packaging materials"},{"value":31,"label":"wood block"},{"value":30,"label":"wood dust"},{"value":74,"label":"wood pallet block"},{"value":41,"label":"wood shaving"}]},"featured_image_src_large":["https:\/\/hnwoodmachine.com\/wp-content\/uploads\/2021\/05\/wood-block-making-machine.jpg",720,405,false],"author_info":{"display_name":"HN-WOOD","author_link":"https:\/\/hnwoodmachine.com\/fr\/author\/woodmachine\/"},"comment_info":0,"category_info":[{"term_id":4,"name":"Product","slug":"product","term_group":0,"term_taxonomy_id":4,"taxonomy":"category","description":"","parent":0,"count":21,"filter":"raw","cat_ID":4,"category_count":21,"category_description":"","cat_name":"Product","category_nicename":"product","category_parent":0}],"tag_info":[{"term_id":75,"name":"packaging materials","slug":"packaging-materials","term_group":0,"term_taxonomy_id":75,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":31,"name":"wood block","slug":"wood-block","term_group":0,"term_taxonomy_id":31,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw"},{"term_id":30,"name":"wood dust","slug":"wood-dust","term_group":0,"term_taxonomy_id":30,"taxonomy":"post_tag","description":"","parent":0,"count":6,"filter":"raw"},{"term_id":74,"name":"wood pallet block","slug":"wood-pallet-block","term_group":0,"term_taxonomy_id":74,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw"},{"term_id":41,"name":"wood shaving","slug":"wood-shaving","term_group":0,"term_taxonomy_id":41,"taxonomy":"post_tag","description":"","parent":0,"count":17,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/posts\/902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/comments?post=902"}],"version-history":[{"count":0,"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/posts\/902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/media\/940"}],"wp:attachment":[{"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/media?parent=902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/categories?post=902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hnwoodmachine.com\/fr\/wp-json\/wp\/v2\/tags?post=902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}